{"id":112,"count":1,"description":"","link":"https:\/\/risabg.com\/blog\/tag\/canadian-film-centre\/","name":"Canadian Film Centre","slug":"canadian-film-centre","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/risabg.com\/blog\/tag\/canadian-film-centre\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/112\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/risabg.com\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/tag\\\/canadian-film-centre\\\/#listItem\",\"name\":\"Canadian Film Centre\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/tag\\\/canadian-film-centre\\\/#listItem\",\"position\":2,\"name\":\"Canadian Film Centre\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/112\\\/#collectionpage\",\"url\":\"https:\\\/\\\/risabg.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/112\\\/\",\"name\":\"Canadian Film Centre | Risa Bramon Garcia\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/112\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/#organization\",\"name\":\"Risa Bramon Garcia\",\"url\":\"https:\\\/\\\/risabg.com\\\/blog\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/risabg.com\\\/blog\\\/\",\"name\":\"Risa Bramon Garcia\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/risabg.com\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Canadian Film Centre | Risa Bramon Garcia","description":"","canonical_url":"https:\/\/risabg.com\/blog\/tag\/canadian-film-centre\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/tags\/112\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/risabg.com\/blog#listItem","position":1,"name":"Home","item":"https:\/\/risabg.com\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/risabg.com\/blog\/tag\/canadian-film-centre\/#listItem","name":"Canadian Film Centre"}},{"@type":"ListItem","@id":"https:\/\/risabg.com\/blog\/tag\/canadian-film-centre\/#listItem","position":2,"name":"Canadian Film Centre","previousItem":{"@type":"ListItem","@id":"https:\/\/risabg.com\/blog#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/tags\/112\/#collectionpage","url":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/tags\/112\/","name":"Canadian Film Centre | Risa Bramon Garcia","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/risabg.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/tags\/112\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/risabg.com\/blog\/#organization","name":"Risa Bramon Garcia","url":"https:\/\/risabg.com\/blog\/"},{"@type":"WebSite","@id":"https:\/\/risabg.com\/blog\/#website","url":"https:\/\/risabg.com\/blog\/","name":"Risa Bramon Garcia","inLanguage":"en-US","publisher":{"@id":"https:\/\/risabg.com\/blog\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/risabg.com\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCanadian Film Centre\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/risabg.com\/blog"},{"label":"Canadian Film Centre","link":"https:\/\/risabg.com\/blog\/tag\/canadian-film-centre\/"}],"_links":{"self":[{"href":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/tags\/112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/risabg.com\/blog\/wp-json\/wp\/v2\/posts?tags=112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}